{"id":1498,"date":"2021-05-25T16:24:51","date_gmt":"2021-05-25T16:24:51","guid":{"rendered":"https:\/\/civil4sl.com\/?post_type=portfolio&#038;p=1498"},"modified":"2024-12-17T12:41:56","modified_gmt":"2024-12-17T12:41:56","slug":"edificio-de-oficinas-p-i-fuente-del-jarro-paterna-valencia","status":"publish","type":"portfolio","link":"https:\/\/civil4sl.com\/es\/proyecto\/edificio-de-oficinas-p-i-fuente-del-jarro-paterna-valencia\/","title":{"rendered":"Edificio de oficinas. P.I. Fuente del Jarro, Paterna (Valencia)"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1498\" class=\"elementor elementor-1498\" data-elementor-post-type=\"portfolio\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-74b61a9 elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"74b61a9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-b9a3e79\" data-id=\"b9a3e79\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a71110d aux-appear-watch-animation aux-fade-in-up-1 elementor-widget elementor-widget-aux-gallery\" data-id=\"a71110d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aux-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"widget-container aux-widget-gallery aux-parent-au05de7ce6\"><div id='aux-gallery-1' class='aux-gallery galleryid-1498 gallery-columns- aux-lightbox-gallery'><div class=\"aux-gallery-container aux-isotope-animated aux-tiles-layout aux-no-gutter aux-layout-packery\"  data-pagination=\"false\" data-lazyload=\"false\" data-perpage=\"24\" data-layout=\"packery\" data-space=\"10\" >    <figure class=\"gallery-item aux-hover-active aux-iso-item  aux-image-box aux-tile-4-4 aux-t-tile-6-6 aux-m-tile-12-12\">\n            <div class=\"\">\n                <a href=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_1-Foto.jpg\" class=\"aux-frame-ratio-inner aux-frame-darken aux-lightbox-btn \" data-elementor-open-lightbox=\"no\" data-original-width=\"1920\" data-original-height=\"1080\" data-caption=\"719_2plantas_vent_simetrica_1 - Foto\">\n                                <div class=\"aux-hover-scale-circle-plus\">\n                        <span class=\"aux-symbol-plus\"><\/span>\n                        <span class=\"aux-symbol-circle\"><\/span>\n                    <\/div>\n                        <img fetchpriority=\"high\" decoding=\"async\" width=\"533\" height=\"533\" src=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_1-Foto-533x533.jpg\" class=\"aux-attachment aux-featured-image attachment-533.33333333333x533.33333333333 aux-attachment-id-1500 \" alt=\"Macfly por Civil4 Ingenier\u00eda\" srcset=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_1-Foto-150x150.jpg 150w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_1-Foto-300x300.jpg 300w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_1-Foto-768x768.jpg 768w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_1-Foto-1024x1024.jpg 1024w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_1-Foto-533x533.jpg 533w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_1-Foto-1910x1910.jpg 1910w\" data-ratio=\"1\" data-original-w=\"1920\" sizes=\"(max-width:479px) 480px,(max-width:767px) 768px,(max-width:1023px) 1024px,533px\" \/>                <\/a>\n            <\/div>\n                <\/figure>\n    <figure class=\"gallery-item aux-hover-active aux-iso-item  aux-image-box aux-tile-4-4 aux-t-tile-6-6 aux-m-tile-12-12\">\n            <div class=\"\">\n                <a href=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_3-Foto.jpg\" class=\"aux-frame-ratio-inner aux-frame-darken aux-lightbox-btn \" data-elementor-open-lightbox=\"no\" data-original-width=\"1920\" data-original-height=\"1080\" data-caption=\"719_2plantas_vent_simetrica_3 - Foto\">\n                                <div class=\"aux-hover-scale-circle-plus\">\n                        <span class=\"aux-symbol-plus\"><\/span>\n                        <span class=\"aux-symbol-circle\"><\/span>\n                    <\/div>\n                        <img decoding=\"async\" width=\"533\" height=\"533\" src=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_3-Foto-533x533.jpg\" class=\"aux-attachment aux-featured-image attachment-533.33333333333x533.33333333333 aux-attachment-id-1503 \" alt=\"719_2plantas_vent_simetrica_3 - Foto\" srcset=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_3-Foto-150x150.jpg 150w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_3-Foto-300x300.jpg 300w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_3-Foto-768x768.jpg 768w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_3-Foto-1024x1024.jpg 1024w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_3-Foto-533x533.jpg 533w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_3-Foto-1910x1910.jpg 1910w\" data-ratio=\"1\" data-original-w=\"1920\" sizes=\"(max-width:479px) 480px,(max-width:767px) 768px,(max-width:1023px) 1024px,533px\" \/>                <\/a>\n            <\/div>\n                <\/figure>\n    <figure class=\"gallery-item aux-hover-active aux-iso-item  aux-image-box aux-tile-4-4 aux-t-tile-6-6 aux-m-tile-12-12\">\n            <div class=\"\">\n                <a href=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_11-Foto.jpg\" class=\"aux-frame-ratio-inner aux-frame-darken aux-lightbox-btn \" data-elementor-open-lightbox=\"no\" data-original-width=\"1920\" data-original-height=\"1080\" data-caption=\"719_2plantas_vent_simetrica_11 - Foto\">\n                                <div class=\"aux-hover-scale-circle-plus\">\n                        <span class=\"aux-symbol-plus\"><\/span>\n                        <span class=\"aux-symbol-circle\"><\/span>\n                    <\/div>\n                        <img decoding=\"async\" width=\"533\" height=\"533\" src=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_11-Foto-533x533.jpg\" class=\"aux-attachment aux-featured-image attachment-533.33333333333x533.33333333333 aux-attachment-id-1505 \" alt=\"719_2plantas_vent_simetrica_11 - Foto\" srcset=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_11-Foto-150x150.jpg 150w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_11-Foto-300x300.jpg 300w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_11-Foto-768x768.jpg 768w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_11-Foto-1024x1024.jpg 1024w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_11-Foto-533x533.jpg 533w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_11-Foto-1910x1910.jpg 1910w\" data-ratio=\"1\" data-original-w=\"1920\" sizes=\"(max-width:479px) 480px,(max-width:767px) 768px,(max-width:1023px) 1024px,533px\" \/>                <\/a>\n            <\/div>\n                <\/figure>\n<\/div><\/div><\/section><!-- widget-container --><style>.aux-parent-au05de7ce6 .aux-frame-ratio { padding-bottom:75% }<\/style>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0f345e2\" data-id=\"0f345e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43da05d aux-appear-watch-animation aux-fade-in-up elementor-widget elementor-widget-aux_modern_heading\" data-id=\"43da05d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><h2 class=\"aux-modern-heading-primary\">INDUSTRIAS<\/h2><h3 class=\"aux-modern-heading-secondary\"><span class=\"aux-head-before\">Edificio de oficinas, P.I. Fuente del Jarro, Paterna (Valencia)<\/span><\/h3><div class=\"aux-modern-heading-divider\"><\/div><\/div>\n        <\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e15a0c aux-appear-watch-animation aux-fade-in-up-1 elementor-widget elementor-widget-text-editor\" data-id=\"2e15a0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Rehabilitaci\u00f3n de edificio de oficinas, en dos plantas, ubicado en pol\u00edgono industrial<\/p><p><strong>Trabajos realizados:<br \/><\/strong>Lay out, dise\u00f1o arquitect\u00f3nico, proyecto de ejecuci\u00f3n y proyecto de actividad.<\/p><p><strong>Superficie:<br \/><\/strong>500 m<sup>2<\/sup><\/p><p><strong>Fecha de realizaci\u00f3n:\u00a0<br \/><\/strong>En ejecuci\u00f3n<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65ab5a1 aux-appear-watch-animation aux-fade-in-up-1 elementor-widget elementor-widget-aux_modern_button\" data-id=\"65ab5a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aux_modern_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"aux-modern-button-wrapper aux-modern-button-align-left\" >\n                    <a class=\"aux-modern-button aux-black aux-modern-button-md aux-modern-button-normal aux-modern-button-default aux-icon-\" href=\"https:\/\/civil4sl.com\/es\/contacto\/\">\n                <div class=\"aux-overlay\"><\/div>\n                                    <div class=\"aux-icon \">\n                                            <\/div>\n                                <div class=\"aux-text\">\n<span class=\"aux-text-before\">CONTACTAR<\/span>                <\/div>\n            <\/a>\n            \n    <\/div>\n\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fb53478 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb53478\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4bb885d\" data-id=\"4bb885d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-da67d4d elementor-widget elementor-widget-post-navigation\" data-id=\"da67d4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation\" role=\"navigation\" aria-label=\"Navegaci\u00f3n de la entrada\">\n\t\t\t<div class=\"elementor-post-navigation__prev elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/civil4sl.com\/es\/proyecto\/supermercado-aldi-2\/\" rel=\"prev\"><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-prev\"><i aria-hidden=\"true\" class=\"fas fa-chevron-circle-left\"><\/i><span class=\"elementor-screen-only\">Ant<\/span><\/span><span class=\"elementor-post-navigation__link__prev\"><span class=\"post-navigation__prev--label\">Proyecto anterior<\/span><span class=\"post-navigation__prev--title\">Edificio comercial, L&#8217;Eliana<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-post-navigation__next elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/civil4sl.com\/es\/proyecto\/restaurante-neighbors\/\" rel=\"next\"><span class=\"elementor-post-navigation__link__next\"><span class=\"post-navigation__next--label\">Proyecto siguiente<\/span><span class=\"post-navigation__next--title\">Restaurante Neighbors<\/span><\/span><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-next\"><i aria-hidden=\"true\" class=\"fas fa-chevron-circle-right\"><\/i><span class=\"elementor-screen-only\">Siguiente<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-36867dc elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"36867dc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ef1d73a\" data-id=\"ef1d73a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b914bac aux-appear-watch-animation aux-fade-in-up elementor-widget elementor-widget-aux_modern_heading\" data-id=\"b914bac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><h2 class=\"aux-modern-heading-primary\">NUESTROS PROYECTOS<\/h2><h3 class=\"aux-modern-heading-secondary\"><span class=\"aux-head-before\">Proyectos <br>relacionados<\/span><\/h3><div class=\"aux-modern-heading-divider\"><\/div><\/div>\n        <\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8c6437 aux-appear-watch-animation aux-fade-in-up elementor-widget elementor-widget-aux_recent_portfolios_grid\" data-id=\"e8c6437\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns&quot;:&quot;4&quot;,&quot;columns_mobile&quot;:&quot;1&quot;}\" data-widget_type=\"aux_recent_portfolios_grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"widget-container aux-widget-recent-portfolios aux-parent-auab00d974\"><div id=\"6a5807c9b22eb\" data-element-id=\"auab00d974\" class=\"aux-portfolio-columns aux-ajax-view aux-isotope-animated aux-isotope-layout aux-layout-grid aux-no-gutter aux-row aux-match-height aux-de-col4 aux-tb-col2 aux-mb-col1 aux-lightbox-gallery\" data-lazyload=\"true\" data-space=\"30\" data-pagination=\"true\" data-deeplink=\"false\" data-slug=\"\" data-perpage=\"8\" data-layout=\"fitRows\" data-reveal-transition-duration=\"600\" data-reveal-between-delay=\"60\" data-hide-transition-duration=\"600\" data-hide-between-delay=\"30\" data-num=\"\" data-order=\"ASC\" data-orderby=\"date\" data-taxonomy=\"\" data-n=\"1088843f6a\"><div class=\"aux-items-loading aux-loading-hide\"><div class=\"aux-loading-loop\"><svg class=\"aux-circle\" width=\"100%\" height=\"100%\" viewBox=\"0 0 42 42\"><circle class=\"aux-stroke-bg\" r=\"20\" cx=\"21\" cy=\"21\" fill=\"none\"><\/circle><circle class=\"aux-progress\" r=\"20\" cx=\"21\" cy=\"21\" fill=\"none\" transform=\"rotate(-90 21 21)\"><\/circle><\/svg><\/div><\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-201 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-gimnasios portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/civil4sl.com\/es\/proyecto\/viva-gym\/\"><img loading=\"lazy\" width=\"340\" height=\"452\" class=\"aux-attachment aux-featured-image attachment-340x452.2 aux-attachment-id-211 \" alt=\"IMG_2108\" data-ratio=\"0.75\" data-original-w=\"1000\" sizes=\"auto\" data-srcset=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2020\/10\/IMG_2108-150x200.jpg 150w,https:\/\/civil4sl.com\/wp-content\/uploads\/2020\/10\/IMG_2108-300x399.jpg 300w,https:\/\/civil4sl.com\/wp-content\/uploads\/2020\/10\/IMG_2108-768x1021.jpg 768w,https:\/\/civil4sl.com\/wp-content\/uploads\/2020\/10\/IMG_2108-340x452.jpg 340w,https:\/\/civil4sl.com\/wp-content\/uploads\/2020\/10\/IMG_2108-990x1316.jpg 990w\" data-src=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2020\/10\/IMG_2108-340x452.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2020\/10\/IMG_2108.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"1000\" data-original-height = \"666\" data-caption = \"IMG_2108\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/civil4sl.com\/es\/proyecto\/viva-gym\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/civil4sl.com\/es\/proyecto\/viva-gym\/\">\n                                                Viva Gym                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/civil4sl.com\/es\/proyecto-cat\/gimnasios\/\" title=\"View all posts in Gimnasios\" rel=\"category\" >Gimnasios<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-257 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-centros-comerciales-y-supermercados portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/civil4sl.com\/es\/proyecto\/supermercado-aldi\/\"><img loading=\"lazy\" width=\"340\" height=\"452\" class=\"aux-attachment aux-featured-image attachment-340x452.2 aux-attachment-id-258 \" alt=\"IMG_2095\" data-ratio=\"0.75\" data-original-w=\"1000\" sizes=\"auto\" data-srcset=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2020\/10\/IMG_2095-150x200.jpg 150w,https:\/\/civil4sl.com\/wp-content\/uploads\/2020\/10\/IMG_2095-300x399.jpg 300w,https:\/\/civil4sl.com\/wp-content\/uploads\/2020\/10\/IMG_2095-768x1021.jpg 768w,https:\/\/civil4sl.com\/wp-content\/uploads\/2020\/10\/IMG_2095-340x452.jpg 340w,https:\/\/civil4sl.com\/wp-content\/uploads\/2020\/10\/IMG_2095-990x1316.jpg 990w\" data-src=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2020\/10\/IMG_2095-340x452.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2020\/10\/IMG_2095.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"1000\" data-original-height = \"697\" data-caption = \"IMG_2095\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/civil4sl.com\/es\/proyecto\/supermercado-aldi\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/civil4sl.com\/es\/proyecto\/supermercado-aldi\/\">\n                                                Supermercado Aldi                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/civil4sl.com\/es\/proyecto-cat\/centros-comerciales-y-supermercados\/\" title=\"View all posts in Centros comerciales y supermercados\" rel=\"category\" >Centros comerciales y supermercados<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-260 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-industrias portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/civil4sl.com\/es\/proyecto\/nave-industrial-en-fuente-del-jarro\/\"><img loading=\"lazy\" width=\"340\" height=\"452\" class=\"aux-attachment aux-featured-image attachment-340x452.2 aux-attachment-id-356 \" alt=\"nave-fuente-del-jarro\" data-ratio=\"0.75\" data-original-w=\"2048\" sizes=\"auto\" data-srcset=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2020\/10\/nave-fuente-del-jarro-150x200.jpg 150w,https:\/\/civil4sl.com\/wp-content\/uploads\/2020\/10\/nave-fuente-del-jarro-300x399.jpg 300w,https:\/\/civil4sl.com\/wp-content\/uploads\/2020\/10\/nave-fuente-del-jarro-768x1021.jpg 768w,https:\/\/civil4sl.com\/wp-content\/uploads\/2020\/10\/nave-fuente-del-jarro-1024x1362.jpg 1024w,https:\/\/civil4sl.com\/wp-content\/uploads\/2020\/10\/nave-fuente-del-jarro-340x452.jpg 340w,https:\/\/civil4sl.com\/wp-content\/uploads\/2020\/10\/nave-fuente-del-jarro-2038x2710.jpg 2038w\" data-src=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2020\/10\/nave-fuente-del-jarro-340x452.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2020\/10\/nave-fuente-del-jarro.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"2048\" data-original-height = \"1700\" data-caption = \"nave-fuente-del-jarro\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/civil4sl.com\/es\/proyecto\/nave-industrial-en-fuente-del-jarro\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/civil4sl.com\/es\/proyecto\/nave-industrial-en-fuente-del-jarro\/\">\n                                                Nave Industrial en Pol\u00edgono Fuente del Jarro                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/civil4sl.com\/es\/proyecto-cat\/industrias\/\" title=\"View all posts in Industrias\" rel=\"category\" >Industrias<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-1498 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-industrias portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/civil4sl.com\/es\/proyecto\/edificio-de-oficinas-p-i-fuente-del-jarro-paterna-valencia\/\"><img loading=\"lazy\" width=\"340\" height=\"452\" class=\"aux-attachment aux-featured-image attachment-340x452.2 aux-attachment-id-1500 \" alt=\"Macfly por Civil4 Ingenier\u00eda\" data-ratio=\"0.75\" data-original-w=\"1920\" sizes=\"auto\" data-srcset=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_1-Foto-150x200.jpg 150w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_1-Foto-300x399.jpg 300w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_1-Foto-768x1021.jpg 768w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_1-Foto-1024x1362.jpg 1024w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_1-Foto-340x452.jpg 340w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_1-Foto-1910x2540.jpg 1910w\" data-src=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_1-Foto-340x452.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/719_2plantas_vent_simetrica_1-Foto.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"1920\" data-original-height = \"1080\" data-caption = \"719_2plantas_vent_simetrica_1 - Foto\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/civil4sl.com\/es\/proyecto\/edificio-de-oficinas-p-i-fuente-del-jarro-paterna-valencia\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/civil4sl.com\/es\/proyecto\/edificio-de-oficinas-p-i-fuente-del-jarro-paterna-valencia\/\">\n                                                Edificio de oficinas. P.I. Fuente del Jarro, Paterna (Valencia)                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/civil4sl.com\/es\/proyecto-cat\/industrias\/\" title=\"View all posts in Industrias\" rel=\"category\" >Industrias<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-1528 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-restaurantes portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/civil4sl.com\/es\/proyecto\/restaurante-neighbors\/\"><img loading=\"lazy\" width=\"340\" height=\"452\" class=\"aux-attachment aux-featured-image attachment-340x452.2 aux-attachment-id-1199 \" alt=\"Interior Neighbors &amp; Co\" data-ratio=\"0.75\" data-original-w=\"1000\" sizes=\"auto\" data-srcset=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/04\/edificio-comercial-eliana-17-150x200.jpg 150w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/04\/edificio-comercial-eliana-17-300x399.jpg 300w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/04\/edificio-comercial-eliana-17-768x1021.jpg 768w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/04\/edificio-comercial-eliana-17-340x452.jpg 340w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/04\/edificio-comercial-eliana-17-990x1316.jpg 990w\" data-src=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/04\/edificio-comercial-eliana-17-340x452.jpg\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/04\/edificio-comercial-eliana-17.jpg\" data-elementor-open-lightbox = \"no\" data-original-width = \"1000\" data-original-height = \"1333\" data-caption = \"edificio-comercial-eliana-17\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/civil4sl.com\/es\/proyecto\/restaurante-neighbors\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/civil4sl.com\/es\/proyecto\/restaurante-neighbors\/\">\n                                                Restaurante Neighbors                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/civil4sl.com\/es\/proyecto-cat\/restaurantes\/\" title=\"View all posts in Restaurantes\" rel=\"category\" >Restaurantes<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                         <article class=\"aux-item-overlay aux-hover-active aux-hover-twoway  post-1551 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-hoteles-y-centros-de-congresos portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                                <div class=\"entry-media aux-frame-boxed-darken aux-frame-zoom \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/civil4sl.com\/es\/proyecto\/hotel-4\/\"><img loading=\"lazy\" width=\"340\" height=\"452\" class=\"aux-attachment aux-featured-image attachment-340x452.2 aux-attachment-id-1458 \" alt=\"Hotel dise\u00f1ado por Civil4 Ingenier\u00eda\" data-ratio=\"0.75\" data-original-w=\"867\" sizes=\"auto\" data-srcset=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/3D-calle-diana-150x200.png 150w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/3D-calle-diana-300x399.png 300w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/3D-calle-diana-768x1021.png 768w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/3D-calle-diana-340x452.png 340w,https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/3D-calle-diana-857x1139.png 857w\" data-src=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/3D-calle-diana-340x452.png\" \/><\/a><\/div>                                <\/div>\n\n                                <div class=\"aux-overlay-content\">\n                                                                        <div class=\"aux-portfolio-overlay-buttons\">\n                                        <div class=\"aux-hover-circle-plus aux-delay-2x\">\n                                            <a href=\"https:\/\/civil4sl.com\/wp-content\/uploads\/2021\/05\/3D-calle-diana.png\" data-elementor-open-lightbox = \"no\" data-original-width = \"867\" data-original-height = \"666\" data-caption = \"Alzado Hotel Denia\" class=\"aux-lightbox-btn \" >\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-plus aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-plus aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n                                        <div class=\"aux-arrow-post-link aux-hover-circle-link\">\n                                            <a href=\"https:\/\/civil4sl.com\/es\/proyecto\/hotel-4\/\">\n                                                <div class=\"aux-arrow-nav aux-round aux-hover-slide aux-outline aux-semi-small aux-white\">\n                                                    <span class=\"aux-overlay\"><\/span>\n                                                    <span class=\"aux-svg-arrow aux-medium-right aux-white\"><\/span>\n                                                    <span class=\"aux-hover-arrow aux-svg-arrow aux-medium-right aux-black\"><\/span>\n                                                <\/div>\n                                            <\/a>\n                                        <\/div>\n\n                                    <\/div>\n                                                                                                            <div class=\"entry-main\">\n\n                                                                        <header class=\"entry-header\">\n                                        <h3 class=\"entry-title aux-hover-move-up\">\n                                            <a href=\"https:\/\/civil4sl.com\/es\/proyecto\/hotel-4\/\">\n                                                Hotel 4*                                            <\/a>\n                                        <\/h3>\n                                    <\/header>\n                                                                                                            <div class=\"entry-info aux-hover-move-up aux-delay-1x\">\n                                        <span class=\"entry-tax\">\n                                                                                        <a href=\"https:\/\/civil4sl.com\/es\/proyecto-cat\/hoteles-y-centros-de-congresos\/\" title=\"View all posts in Hoteles y Centros de Congresos\" rel=\"category\" >Hoteles y Centros de Congresos<\/a>                                        <\/span>\n                                    <\/div>\n                                                                                                            <\/div>\n                                                                <\/div>\n                        <\/article>\n<\/div><\/div><script type=\"text\/javascript\">var auab00d974AjaxConfig = {\"title\":\"\",\"cat\":[\"16\",\"17\",\"18\",\"19\",\"37\"],\"num\":\"\",\"only_posts__in\":\"\",\"include\":\"\",\"exclude\":\"\",\"posts_per_page\":-1,\"offset\":\"\",\"order_by\":\"date\",\"order\":\"ASC\",\"exclude_without_media\":\"yes\",\"display_like\":\"no\",\"deeplink\":\"\",\"use_ajax\":\"no\",\"deeplink_slug\":null,\"show_filters\":\"\",\"filter_by\":null,\"filter_style\":null,\"filter_align\":null,\"reveal_transition_duration\":\"600\",\"reveal_between_delay\":\"60\",\"hide_transition_duration\":\"600\",\"hide_between_delay\":\"30\",\"item_style\":\"overlay-lightbox-boxed\",\"tile_style_pattern\":\"default\",\"tiles_item_style\":\"overlay\",\"entry_background_color\":\"\",\"entry_border_color\":\"\",\"paginate\":\"yes\",\"perpage\":\"8\",\"crop\":true,\"display_title\":\"yes\",\"show_info\":\"yes\",\"display_read_more\":false,\"image_aspect_ratio\":\"1.33\",\"space\":\"30\",\"desktop_cnum\":\"4\",\"tablet_cnum\":\"2\",\"phone_cnum\":\"1\",\"layout\":\"grid\",\"tag\":\"\",\"filter\":\"\",\"extra_classes\":\"\",\"extra_column_classes\":\"\",\"custom_el_id\":\"\",\"template_part_file\":\"recent-portfolio\",\"extra_template_path\":\"\\\/home\\\/civil\\\/domains\\\/civil4sl.com\\\/public_html\\\/wp-content\\\/plugins\\\/auxin-portfolio\\\/public\\\/templates\\\/elements\",\"universal_id\":\"auab00d974\",\"query_args\":[],\"term\":\"\",\"reset_query\":true,\"use_wp_query\":false,\"wp_query_args\":[],\"custom_wp_query\":\"\",\"loadmore_type\":null,\"loadmore_label\":null,\"loadmore_per_page\":12,\"term_field\":\"slug\",\"base\":\"aux_recent_portfolios_grid\",\"base_class\":\"aux-widget-recent-portfolios\",\"paged\":\"\",\"override_global_query\":false,\"content\":null,\"skip_wrappers\":false,\"content_width\":1600,\"inview_transition\":\"none\",\"inview_duration\":\"\",\"inview_delay\":\"\",\"inview_repeat\":\"no\",\"inview_offset\":\"\",\"called_from\":\"elementor\"};<\/script><\/section><!-- widget-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ea93b9 elementor-widget elementor-widget-aux_modern_button\" data-id=\"9ea93b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"aux_modern_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"aux-modern-button-wrapper aux-modern-button-align-right\" >\n                    <a class=\"aux-modern-button aux-black aux-modern-button-md aux-modern-button-normal aux-modern-button-default aux-icon-right\">\n                <div class=\"aux-overlay\"><\/div>\n                                    <div class=\"aux-icon \">\n                        <i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>                    <\/div>\n                                <div class=\"aux-text\">\n<span class=\"aux-text-before\">VER TODOS LOS PROYECTOS<\/span>                <\/div>\n            <\/a>\n            \n    <\/div>\n\n    \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>INDUSTRIAS Edificio de oficinas, P.I. Fuente del Jarro, Paterna (Valencia) Rehabilitaci\u00f3n de edificio de oficinas, en dos plantas, ubicado en pol\u00edgono industrial Trabajos realizados:Lay out, dise\u00f1o arquitect\u00f3nico, proyecto de ejecuci\u00f3n y proyecto de actividad. Superficie:500 m2 Fecha de realizaci\u00f3n:\u00a0En ejecuci\u00f3n CONTACTAR NUESTROS PROYECTOS Proyectos relacionados Viva Gym Gimnasios Supermercado Aldi Centros comerciales y supermercados Nave [&hellip;]<\/p>\n","protected":false},"featured_media":1500,"menu_order":0,"template":"elementor_header_footer","meta":{"footnotes":""},"portfolio-cat":[19],"portfolio-tag":[13],"portfolio-filter":[14],"class_list":["post-1498","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio-cat-industrias","portfolio-tag-uncategorized","portfolio-filter-uncategorized"],"_links":{"self":[{"href":"https:\/\/civil4sl.com\/es\/wp-json\/wp\/v2\/portfolio\/1498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/civil4sl.com\/es\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/civil4sl.com\/es\/wp-json\/wp\/v2\/types\/portfolio"}],"version-history":[{"count":38,"href":"https:\/\/civil4sl.com\/es\/wp-json\/wp\/v2\/portfolio\/1498\/revisions"}],"predecessor-version":[{"id":1928,"href":"https:\/\/civil4sl.com\/es\/wp-json\/wp\/v2\/portfolio\/1498\/revisions\/1928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/civil4sl.com\/es\/wp-json\/wp\/v2\/media\/1500"}],"wp:attachment":[{"href":"https:\/\/civil4sl.com\/es\/wp-json\/wp\/v2\/media?parent=1498"}],"wp:term":[{"taxonomy":"portfolio-cat","embeddable":true,"href":"https:\/\/civil4sl.com\/es\/wp-json\/wp\/v2\/portfolio-cat?post=1498"},{"taxonomy":"portfolio-tag","embeddable":true,"href":"https:\/\/civil4sl.com\/es\/wp-json\/wp\/v2\/portfolio-tag?post=1498"},{"taxonomy":"portfolio-filter","embeddable":true,"href":"https:\/\/civil4sl.com\/es\/wp-json\/wp\/v2\/portfolio-filter?post=1498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}